{"id":3547,"date":"2025-03-02T22:30:47","date_gmt":"2025-03-02T22:30:47","guid":{"rendered":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/?post_type=proyecto&#038;p=3547"},"modified":"2025-03-02T22:30:53","modified_gmt":"2025-03-02T22:30:53","slug":"lucia-granadoss-portfolio","status":"publish","type":"proyecto","link":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/en\/proyecto\/lucia-granadoss-portfolio\/","title":{"rendered":"Luc\u00eda Granados's portfolio"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":68,"featured_media":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[54],"class_list":["post-3547","proyecto","type-proyecto","status-publish","hentry","category-portfolio-eng"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Luc\u00eda Granados&#039;s portfolio - Ilus.Galer\u00eda<\/title>\n<meta name=\"description\" content=\"&quot;Proyectos de Ilus.Galer\u00eda, realizados en el marco del Programa de Actualizaci\u00f3n en Ilustraci\u00f3n Profesional de la Universidad de Buenos Aires, reflejando creatividad y aprendizaje acad\u00e9mico.&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/en\/proyecto\/lucia-granadoss-portfolio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luc\u00eda Granados&#039;s portfolio - Ilus.Galer\u00eda\" \/>\n<meta property=\"og:description\" content=\"&quot;Proyectos de Ilus.Galer\u00eda, realizados en el marco del Programa de Actualizaci\u00f3n en Ilustraci\u00f3n Profesional de la Universidad de Buenos Aires, reflejando creatividad y aprendizaje acad\u00e9mico.&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/en\/proyecto\/lucia-granadoss-portfolio\/\" \/>\n<meta property=\"og:site_name\" content=\"Ilus.Galer\u00eda\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-02T22:30:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/wp-content\/uploads\/2024\/11\/ilus-galeria-seo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"ScholarlyArticle\",\"@id\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/en\/proyecto\/lucia-granadoss-portfolio\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/en\/proyecto\/lucia-granadoss-portfolio\/\"},\"author\":{\"name\":\"Luc\u00eda Granados\",\"@id\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/#\/schema\/person\/b8f88cc15861faffc6a70f992da6904b\"},\"headline\":\"Luc\u00eda Granados's portfolio\",\"datePublished\":\"2025-03-02T22:30:47+00:00\",\"dateModified\":\"2025-03-02T22:30:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/en\/proyecto\/lucia-granadoss-portfolio\/\"},\"wordCount\":5,\"publisher\":{\"@id\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/#organization\"},\"articleSection\":[\"Portfolio\"],\"inLanguage\":\"es-AR\"},{\"@type\":[\"WebPage\",\"CollectionPage\"],\"@id\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/en\/proyecto\/lucia-granadoss-portfolio\/\",\"url\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/en\/proyecto\/lucia-granadoss-portfolio\/\",\"name\":\"Luc\u00eda Granados's portfolio - Ilus.Galer\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/#website\"},\"datePublished\":\"2025-03-02T22:30:47+00:00\",\"dateModified\":\"2025-03-02T22:30:53+00:00\",\"description\":\"\\\"Proyectos de Ilus.Galer\u00eda, realizados en el marco del Programa de Actualizaci\u00f3n en Ilustraci\u00f3n Profesional de la Universidad de Buenos Aires, reflejando creatividad y aprendizaje acad\u00e9mico.\\\"\",\"breadcrumb\":{\"@id\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/en\/proyecto\/lucia-granadoss-portfolio\/#breadcrumb\"},\"inLanguage\":\"es-AR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/en\/proyecto\/lucia-granadoss-portfolio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/proyecto\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Luc\u00eda Granados's portfolio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/#website\",\"url\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/\",\"name\":\"Ilus.Galer\u00eda\",\"description\":\"Programa de Actualizaci\u00f3n en Ilustraci\u00f3n Profesional de la Facultad de Arquitectura, Dise\u00f1o y Urbanismo de la Universidad de Buenos Aires\",\"publisher\":{\"@id\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/#organization\"},\"alternateName\":\"Programa de Ilustraci\u00f3n Profesional de la Facultad de Arquitectura y Urbanismo de la Universidad de Buenos Aires\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/#organization\",\"name\":\"Programa de Ilustraci\u00f3n Profesional de la Facultad de Arquitectura y Urbanismo de la Universidad de Buenos Aires\",\"alternateName\":\"Ilus.P\",\"url\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/wp-content\/uploads\/2024\/11\/ilus-galeria-seo.png\",\"contentUrl\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/wp-content\/uploads\/2024\/11\/ilus-galeria-seo.png\",\"width\":1024,\"height\":1024,\"caption\":\"Programa de Ilustraci\u00f3n Profesional de la Facultad de Arquitectura y Urbanismo de la Universidad de Buenos Aires\"},\"image\":{\"@id\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/ilusposgrado\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/#\/schema\/person\/b8f88cc15861faffc6a70f992da6904b\",\"name\":\"Luc\u00eda Granados\",\"description\":\"Soy colombiana de nacimiento y argentina por elecci\u00f3n. Nac\u00ed en Bogot\u00e1, pero hace 13 a\u00f1os vivo en Mar del Plata con mi esposo e hijo. Estudi\u00e9 ingenier\u00eda qu\u00edmica y trabaj\u00e9 ocho a\u00f1os en el \u00e1rea, pero en 2019 decid\u00ed seguir mi pasi\u00f3n por las artes visuales. Desde entonces, he estudiado ilustraci\u00f3n y participado en talleres en Buenos Aires y Mar del Plata. Actualmente, curso un posgrado en ilustraci\u00f3n en la UBA. Creo que la vocaci\u00f3n se descubre a su tiempo, si estamos dispuestos a cambiar, aunque no sea f\u00e1cil\",\"sameAs\":[\"https:\/\/luciagranadosilustradora.myportfolio.com\/ilustracion-editorial\",\"https:\/\/www.instagram.com\/laluchitagranados\/\"],\"url\":\"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/ilustrador\/mariagonzalezgranados\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luc\u00eda Granados's portfolio - Ilus.Galer\u00eda","description":"\"Proyectos de Ilus.Galer\u00eda, realizados en el marco del Programa de Actualizaci\u00f3n en Ilustraci\u00f3n Profesional de la Universidad de Buenos Aires, reflejando creatividad y aprendizaje acad\u00e9mico.\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/en\/proyecto\/lucia-granadoss-portfolio\/","og_locale":"es_ES","og_type":"article","og_title":"Luc\u00eda Granados's portfolio - Ilus.Galer\u00eda","og_description":"\"Proyectos de Ilus.Galer\u00eda, realizados en el marco del Programa de Actualizaci\u00f3n en Ilustraci\u00f3n Profesional de la Universidad de Buenos Aires, reflejando creatividad y aprendizaje acad\u00e9mico.\"","og_url":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/en\/proyecto\/lucia-granadoss-portfolio\/","og_site_name":"Ilus.Galer\u00eda","article_modified_time":"2025-03-02T22:30:53+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/wp-content\/uploads\/2024\/11\/ilus-galeria-seo.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ScholarlyArticle","@id":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/en\/proyecto\/lucia-granadoss-portfolio\/#article","isPartOf":{"@id":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/en\/proyecto\/lucia-granadoss-portfolio\/"},"author":{"name":"Luc\u00eda Granados","@id":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/#\/schema\/person\/b8f88cc15861faffc6a70f992da6904b"},"headline":"Luc\u00eda Granados's portfolio","datePublished":"2025-03-02T22:30:47+00:00","dateModified":"2025-03-02T22:30:53+00:00","mainEntityOfPage":{"@id":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/en\/proyecto\/lucia-granadoss-portfolio\/"},"wordCount":5,"publisher":{"@id":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/#organization"},"articleSection":["Portfolio"],"inLanguage":"es-AR"},{"@type":["WebPage","CollectionPage"],"@id":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/en\/proyecto\/lucia-granadoss-portfolio\/","url":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/en\/proyecto\/lucia-granadoss-portfolio\/","name":"Luc\u00eda Granados's portfolio - Ilus.Galer\u00eda","isPartOf":{"@id":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/#website"},"datePublished":"2025-03-02T22:30:47+00:00","dateModified":"2025-03-02T22:30:53+00:00","description":"\"Proyectos de Ilus.Galer\u00eda, realizados en el marco del Programa de Actualizaci\u00f3n en Ilustraci\u00f3n Profesional de la Universidad de Buenos Aires, reflejando creatividad y aprendizaje acad\u00e9mico.\"","breadcrumb":{"@id":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/en\/proyecto\/lucia-granadoss-portfolio\/#breadcrumb"},"inLanguage":"es-AR"},{"@type":"BreadcrumbList","@id":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/en\/proyecto\/lucia-granadoss-portfolio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/proyecto\/"},{"@type":"ListItem","position":3,"name":"Luc\u00eda Granados's portfolio"}]},{"@type":"WebSite","@id":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/#website","url":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/","name":"Ilus.Galer\u00eda","description":"Programa de Actualizaci\u00f3n en Ilustraci\u00f3n Profesional de la Facultad de Arquitectura, Dise\u00f1o y Urbanismo de la Universidad de Buenos Aires","publisher":{"@id":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/#organization"},"alternateName":"Programa de Ilustraci\u00f3n Profesional de la Facultad de Arquitectura y Urbanismo de la Universidad de Buenos Aires","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/#organization","name":"Programa de Ilustraci\u00f3n Profesional de la Facultad de Arquitectura y Urbanismo de la Universidad de Buenos Aires","alternateName":"Ilus.P","url":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/#\/schema\/logo\/image\/","url":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/wp-content\/uploads\/2024\/11\/ilus-galeria-seo.png","contentUrl":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/wp-content\/uploads\/2024\/11\/ilus-galeria-seo.png","width":1024,"height":1024,"caption":"Programa de Ilustraci\u00f3n Profesional de la Facultad de Arquitectura y Urbanismo de la Universidad de Buenos Aires"},"image":{"@id":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/ilusposgrado\/"]},{"@type":"Person","@id":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/#\/schema\/person\/b8f88cc15861faffc6a70f992da6904b","name":"Luc\u00eda Granados","description":"Soy colombiana de nacimiento y argentina por elecci\u00f3n. Nac\u00ed en Bogot\u00e1, pero hace 13 a\u00f1os vivo en Mar del Plata con mi esposo e hijo. Estudi\u00e9 ingenier\u00eda qu\u00edmica y trabaj\u00e9 ocho a\u00f1os en el \u00e1rea, pero en 2019 decid\u00ed seguir mi pasi\u00f3n por las artes visuales. Desde entonces, he estudiado ilustraci\u00f3n y participado en talleres en Buenos Aires y Mar del Plata. Actualmente, curso un posgrado en ilustraci\u00f3n en la UBA. Creo que la vocaci\u00f3n se descubre a su tiempo, si estamos dispuestos a cambiar, aunque no sea f\u00e1cil","sameAs":["https:\/\/luciagranadosilustradora.myportfolio.com\/ilustracion-editorial","https:\/\/www.instagram.com\/laluchitagranados\/"],"url":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/ilustrador\/mariagonzalezgranados\/"}]}},"_links":{"self":[{"href":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/wp-json\/wp\/v2\/proyecto\/3547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/wp-json\/wp\/v2\/proyecto"}],"about":[{"href":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/wp-json\/wp\/v2\/types\/proyecto"}],"author":[{"embeddable":true,"href":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/wp-json\/wp\/v2\/users\/68"}],"version-history":[{"count":1,"href":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/wp-json\/wp\/v2\/proyecto\/3547\/revisions"}],"predecessor-version":[{"id":3548,"href":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/wp-json\/wp\/v2\/proyecto\/3547\/revisions\/3548"}],"wp:attachment":[{"href":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/wp-json\/wp\/v2\/media?parent=3547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ilusposgrado.com.ar\/ilusgaleria\/wp-json\/wp\/v2\/categories?post=3547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}